{"id":8839,"date":"2025-05-19T11:58:42","date_gmt":"2025-05-19T10:58:42","guid":{"rendered":"https:\/\/unitedhandsforrefugees.org\/?page_id=8839"},"modified":"2025-06-26T23:14:07","modified_gmt":"2025-06-26T22:14:07","slug":"gbv-campaign-2025","status":"publish","type":"page","link":"https:\/\/unitedhandsforrefugees.org\/de\/gbv-campaign-2025\/","title":{"rendered":"GBV Campaign 2025"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8839\" class=\"elementor elementor-8839\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-23f5724 e-con-full e-flex e-con e-parent\" data-id=\"23f5724\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-204b468 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"204b468\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2025 Kampagne<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d1132e elementor-widget-mobile__width-inherit sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"3d1132e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Schutz und Gerechtigkeit f\u00fcr jesidische \u00dcberlebende \u2013<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2cbff2 elementor-widget-mobile__width-auto sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"e2cbff2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gegen die anhaltende sexualisierte<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0612c40 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"0612c40\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gewalt an Frauen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-9223c70 e-con-full e-flex e-con e-parent\" data-id=\"9223c70\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39e818c elementor-widget-mobile__width-inherit sc_fly_static elementor-widget elementor-widget-image\" data-id=\"39e818c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-9043\" alt=\"\" srcset=\"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-150x150.png 150w, https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-11x12.png 11w, https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-90x90.png 90w, https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-370x370.png 370w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e56230 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"0e56230\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-quote-left\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 256h-80v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8c-88.4 0-160 71.6-160 160v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48zm-288 0H96v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8C71.6 32 0 103.6 0 192v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIm Namen von uns allen bitten wir darum, unser ersch\u00fctterndes Schweigen zu h\u00f6ren.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-dddeb4c e-flex e-con-boxed e-con e-parent\" data-id=\"dddeb4c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eee3d8b elementor-align-center sc_fly_static elementor-widget elementor-widget-button\" data-id=\"eee3d8b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#donate\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Spenden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-307e020 e-con-full e-flex e-con e-parent\" data-id=\"307e020\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-631c58f elementor-widget-divider--view-line sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"631c58f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-37df834 e-con-full e-flex e-con e-parent\" data-id=\"37df834\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4985c95 elementor-widget__width-initial elementor-widget-mobile__width-inherit sc_fly_static elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"4985c95\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 1\"><div class=\"layoutArea\"><div class=\"column\"><p>Im August 2014 \u00fcberfiel der sogenannte IS die jesidische Bev\u00f6lkerung in Sinjar im Nordirak. Dabei wurden \u00fcber 5.000 M\u00e4nner ermordet, mehr als 10.000 Frauen und Kinder verschleppt und versklavt sowie \u00fcber 400.000 Jesid:innen in die Flucht getrieben.<\/p><p>Fast elf Jahre nach dem <a href=\"https:\/\/unitedhandsforrefugees.org\/de\/yazidi-support-program\/\"><strong>Genozid an den Jesid:innen<\/strong><\/a>leben viele \u00dcberlebende noch immer unter extrem schwierigen Bedingungen: Sie sind weiterhin vertrieben, gefangen in \u00fcberf\u00fcllten, unw\u00fcrdigen Lagern oder schutzlos in St\u00e4dten, in denen sie Ausgrenzung und Ausbeutung erfahren. Gerechtigkeit und Sicherheit bleiben ihnen verwehrt, und eine R\u00fcckkehr in ihre Heimat ist f\u00fcr die meisten unm\u00f6glich. Ihr Leid ist nicht Vergangenheit \u2013 es ist eine andauernde, tiefgreifende Krise. Solange es keine wirksamen Strukturen zum Schutz gibt, keine rechtliche Unterst\u00fctzung, keine Aussicht auf humanit\u00e4re Aufnahme und keine konsequente Strafverfolgung der T\u00e4ter, bleibt den Jesid:innen die Chance auf einen Neuanfang verwehrt. Ihr Trauma wird durch das weltweite Schweigen noch versch\u00e4rft \u2013 denn der Genozid hat nie wirklich aufgeh\u00f6rt. Er setzt sich fort, langsam und lautlos, besonders in der anhaltenden Gewalt gegen Frauen und M\u00e4dchen.<\/p><p>Wir m\u00fcssen jetzt handeln \u2013 ihre Geschichten anh\u00f6ren, ihre Rechte verteidigen, Gerechtigkeit einfordern und uns daf\u00fcr einsetzen, dass sie in Sicherheit, W\u00fcrde und Freiheit leben k\u00f6nnen.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-224f4b7 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"224f4b7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/Artboard-4-819x1024.png\" class=\"attachment-large size-large wp-image-9127\" alt=\"\" srcset=\"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/Artboard-4-819x1024.png 819w, https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/Artboard-4-240x300.png 240w, https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/Artboard-4-768x960.png 768w, https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/Artboard-4-10x12.png 10w, https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/Artboard-4-370x463.png 370w, https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/Artboard-4.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-215de58 e-con-full e-flex e-con e-parent\" data-id=\"215de58\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-238da6e elementor-widget-divider--view-line sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"238da6e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-18fbf13 e-con-full e-flex e-con e-parent\" data-id=\"18fbf13\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9eabc67 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"9eabc67\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anhaltende geschlechtsspezifische Gewalt:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76e85b8 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"76e85b8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Systematische sexuelle Ausbeutung jesidischer Frauen und M\u00e4dchen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cab418 sc_fly_static elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1cab418\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jesidische Frauen und M\u00e4dchen sind in besonderem Ma\u00dfe von den Folgen des Genozids von 2014 betroffen, der vor allem durch sexualisierte und geschlechtsbasierte Gewalt gepr\u00e4gt war.\nDer Genozid an den Jesid:innen im Jahr 2014\nDie systematische Versklavung, Vergewaltigung und Entmenschlichung haben tiefe Spuren hinterlassen, die bis heute nachwirken und f\u00fcr Tausende Jesidinnen nach wie vor Realit\u00e4t sind. Sowohl im Irak als auch in den Transitl\u00e4ndern, in denen Jesid:innen weiterhin vertrieben leben fehlt es bis heute an strukturellem Schutz f\u00fcr Jesidinnen, w\u00e4hrend die T\u00e4ter weitgehend straflos bleiben. Das institutionelle Veragen und die fehlenden Konsequenzen beg\u00fcnstigt die anhaltende Ausbeutung von Jesidinnen und M\u00e4dchen und versch\u00e4rft deren Auswirkungen innerhalb der Gemeinschaft.<\/p><p>Berichte zeigen systematische sexuelle Ausbeutung durch Vermieter, Vorgesetzte, Beamte und andere Autorit\u00e4tspersonen, die die prek\u00e4re Lage der Betroffenen ausnutzen und sie unter Bedrohung ihrer Existenz missbrauchen. Diese Form der Ausbeutung weist in allen F\u00e4llen eine alarmierende Systematik auf, wie die Aussagen von Betroffenen aus der von uns unterst\u00fctzten Community verdeutlicht:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b8eb5f elementor-headline--style-highlight sc_fly_static elementor-widget elementor-widget-animated-headline\" data-id=\"7b8eb5f\" data-element_type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline&quot;,&quot;highlighted_text&quot;:&quot;I live at the mercy of my landlord. &quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">\"<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">Ich bin meinem Vermieter ausgeliefert. <\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Er kommt, wann immer er will, in meine Wohnung und erwartet, dass ich mich seinen W\u00fcnschen beuge. Im Gegenzug verlangt er keine Miete, aber manchmal fordert er dennoch Geld f\u00fcr Rechnungen. Er repariert nichts in der Wohnung. Ich habe diesem Arrangement nie zugestimmt, doch ich habe keine Wahl. Wenn ich mich weigere, droht er, meine Familie auf die Stra\u00dfe zu setzen, ohne dass uns jemand helfen wird.\"<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-237adfd elementor-headline--style-highlight sc_fly_static elementor-widget elementor-widget-animated-headline\" data-id=\"237adfd\" data-element_type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline&quot;,&quot;highlighted_text&quot;:&quot;I live at the mercy of the man&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">\"<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">Ich bin dem Manager der Textilfabrik, in der ich arbeite, ausgeliefert<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Er fordert mich auf, mit\nihm zu gehen und seine W\u00fcnsche zu erf\u00fcllen. Falls ich mich weigere, werde ich nicht bezahlt und er sorgt daf\u00fcr, dass ich nirgendwo sonst arbeiten kann. Aber ich muss arbeiten, um meine Familie zu unterst\u00fctzen.\"<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c17ed44 sc_fly_static elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c17ed44\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In mindestens einem uns gekannten Fall f\u00fchrte diese systematische Ausbeutung sogar zum Mord an einer jesidischen Frau in 2021, ohne dass echte Konsequenzen f\u00fcr die T\u00e4ter folgten. Der Ernst der Lage wird durch die Worte einer anderen Jesidin verdeutlicht, die sagt:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-131f562 elementor-headline--style-highlight sc_fly_static elementor-widget elementor-widget-animated-headline\" data-id=\"131f562\" data-element_type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline&quot;,&quot;highlighted_text&quot;:&quot;the consequences of speaking out are too great and too real&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Aus Angst kann ich nicht sprechen. Ich kann nicht direkt sagen, womit ich konfrontiert bin,<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">weil die Konsequenzen, mich zu \u00e4u\u00dfern, zu gro\u00df und zu real sind.<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">.\"<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd72d1a sc_fly_static elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"dd72d1a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 2\"><div class=\"layoutArea\"><div class=\"column\"><p>Die Frauen und M\u00e4dchen sehen sich au\u00dferstande, offen Widerstand zu leisten oder \u00fcber ihre Situation zu sprechen. Nach Jahren der Verfolgung und Unterdr\u00fcckung \u00fcberwiegt die Angst vor weiteren Repressalien. Sie leben in st\u00e4ndiger Unsicherheit, ohne Aussicht auf wirksamen Schutz oder Gerechtigkeit. Die Institutionen, die Schutz und Gerechtigkeit bieten sollten, haben sie wiederholt im Stich gelassen \u2013 stattdessen leben sie weiterhin in st\u00e4ndiger Unsicherheit.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3fa4b0 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"d3fa4b0\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-quote-left\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 256h-80v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8c-88.4 0-160 71.6-160 160v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48zm-288 0H96v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8C71.6 32 0 103.6 0 192v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIm Namen von uns allen bitten wir darum, unser ersch\u00fctterndes Schweigen zu h\u00f6ren.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-be3afc9 e-flex e-con-boxed e-con e-parent\" data-id=\"be3afc9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37f5f15 elementor-align-center sc_fly_static elementor-widget elementor-widget-button\" data-id=\"37f5f15\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#donate\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Donate Here<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1643a4b elementor-section-stretched scheme_default elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1643a4b\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31aacd5 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"31aacd5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87453d4 sc_fly_static elementor-invisible elementor-widget elementor-widget-trx_sc_title\" data-id=\"87453d4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"trx_sc_title_1508268643\"\r\n\t\tclass=\"sc_title  text_position_horizontal sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag trx_addons_inline_889323411\"><span class=\"sc_item_title_text\">Was macht United Hands for Refugees?<\/span><\/h3><\/div><!-- \/.sc_title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e4d134 elementor-widget__width-initial elementor-widget-mobile__width-inherit sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"8e4d134\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>United Hands for Refugees (UHfR) ist eine in Deutschland registrierte, ehrenamtlich gef\u00fchrte NGO, die sich seit 2020 f\u00fcr marginalisierte und vertriebene Communities einsetzt. Ein besonderer Fokus liegt auf der Unterst\u00fctzung jesidischer Genozid-\u00dcberlebender, die unter besonders grausamen und unsicheren Bedingungen nach wie vor auf der Flucht sind. UHfR arbeitet eng mit Betroffenen und Vertreter:innen der jesidischen Diaspora zusammen, um konkrete Hilfe zu leisten, Teilhabe zu erm\u00f6glichen und langfristige Perspektiven zu schaffen \u2013 stets im Einklang mit den grundlegenden Menschenrechten.<\/p><p>Mit deiner Spende unterst\u00fctzt du die Ziele unseres Supportprogramms f\u00fcr die jesidische Community:<\/p><p>1. <b>Soforthilfe f\u00fcr \u00dcberlebende des Genozids<\/b> in Form von lebensnotwendigen Ressourcen (Kleidung, Nahrungsmittel, Hygiene- und Haushaltsartikel), medizinischer Versorgung, kultureller St\u00e4rkung sowie Rechtsvertretung f\u00fcr humanit\u00e4re Aufnahmen und gegen illegale Abschiebungen.<\/p><p>2. <b>Ausbau von Kapazit\u00e4ten und St\u00e4rkung zivilgesellschaftlicher Hilfsnetzwerke<\/b> in Europa und Australien durch gezielte Zusammenarbeit.<\/p><p>3. <b>F\u00f6rderung langfristiger Schutzma\u00dfnahmen<\/b> und Zugang zu humanit\u00e4ren Aufnahmeprogrammen durch gemeinsames zivilgesellschaftliches Engagement.<\/p><p>4. <b>Beitrag zu den langfristigen Bem\u00fchungen<\/b>, Staaten wie E\udbff\udc00-Mitglieder und Australien in die Verantwortung zu nehmen, ihren menschenrechtlichen Verpflichtungen nachzukommen.<\/p><p>UHfR gew\u00e4hrleistet den Schutz der Frauen durch absolute Diskretion: Namen, Orte und pers\u00f6nliche Details bleiben vertraulich. Dies ist Grundlage unseres ethischen Ansatzes, der Betroffene in den Mittelpunkt stellt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-674aa61 e-flex e-con-boxed e-con e-parent\" data-id=\"674aa61\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1c64d8b e-con-full e-flex e-con e-child\" data-id=\"1c64d8b\" data-element_type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-93dbd76 e-con-full e-flex e-con e-child\" data-id=\"93dbd76\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6b2237 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"c6b2237\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Wie k\u00f6nnt ihr uns unterst\u00fctzen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-756bfb9 e-con-full e-flex e-con e-child\" data-id=\"756bfb9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5191ba2 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"5191ba2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit euren Spenden unterst\u00fctzt ihr direkt jesidische Frauen und \u00dcberlebende des Genozids, die sexualisierter und geschlechtsspezifischer Gewalt ausgesetzt sind \u2013 sowie ihre betroffenen Familien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-24dfdb9 e-con-full e-flex e-con e-child\" data-id=\"24dfdb9\" data-element_type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e03b850 e-con-full e-flex e-con e-child\" data-id=\"e03b850\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1222eef elementor-view-default elementor-position-top elementor-mobile-position-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"1222eef\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-donate\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 416c114.9 0 208-93.1 208-208S370.9 0 256 0 48 93.1 48 208s93.1 208 208 208zM233.8 97.4V80.6c0-9.2 7.4-16.6 16.6-16.6h11.1c9.2 0 16.6 7.4 16.6 16.6v17c15.5.8 30.5 6.1 43 15.4 5.6 4.1 6.2 12.3 1.2 17.1L306 145.6c-3.8 3.7-9.5 3.8-14 1-5.4-3.4-11.4-5.1-17.8-5.1h-38.9c-9 0-16.3 8.2-16.3 18.3 0 8.2 5 15.5 12.1 17.6l62.3 18.7c25.7 7.7 43.7 32.4 43.7 60.1 0 34-26.4 61.5-59.1 62.4v16.8c0 9.2-7.4 16.6-16.6 16.6h-11.1c-9.2 0-16.6-7.4-16.6-16.6v-17c-15.5-.8-30.5-6.1-43-15.4-5.6-4.1-6.2-12.3-1.2-17.1l16.3-15.5c3.8-3.7 9.5-3.8 14-1 5.4 3.4 11.4 5.1 17.8 5.1h38.9c9 0 16.3-8.2 16.3-18.3 0-8.2-5-15.5-12.1-17.6l-62.3-18.7c-25.7-7.7-43.7-32.4-43.7-60.1.1-34 26.4-61.5 59.1-62.4zM480 352h-32.5c-19.6 26-44.6 47.7-73 64h63.8c5.3 0 9.6 3.6 9.6 8v16c0 4.4-4.3 8-9.6 8H73.6c-5.3 0-9.6-3.6-9.6-8v-16c0-4.4 4.3-8 9.6-8h63.8c-28.4-16.3-53.3-38-73-64H32c-17.7 0-32 14.3-32 32v96c0 17.7 14.3 32 32 32h448c17.7 0 32-14.3 32-32v-96c0-17.7-14.3-32-32-32z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSPENDEN\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSofort spenden\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de9cb05 sc_layouts_hide_on_wide sc_layouts_hide_on_desktop sc_layouts_hide_on_notebook sc_layouts_hide_on_tablet sc_fly_static elementor-widget elementor-widget-button\" data-id=\"de9cb05\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#donate\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Donate Here<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1728f71 e-con-full e-flex e-con e-child\" data-id=\"1728f71\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b985725 elementor-view-default elementor-position-top elementor-mobile-position-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"b985725\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tF\u00d6RDERMITGLIEDSCHAFT\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWerde Mitglied und unterst\u00fctze monatlich\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f81002a sc_fly_static elementor-widget elementor-widget-button\" data-id=\"f81002a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/unitedhandsforrefugees.org\/de\/sponsoring-member-registration\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hier Registrieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1d21733 e-con-full e-flex e-con e-child\" data-id=\"1d21733\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf08901 elementor-view-default elementor-position-top elementor-mobile-position-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"cf08901\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-handshake\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M434.7 64h-85.9c-8 0-15.7 3-21.6 8.4l-98.3 90c-.1.1-.2.3-.3.4-16.6 15.6-16.3 40.5-2.1 56 12.7 13.9 39.4 17.6 56.1 2.7.1-.1.3-.1.4-.2l79.9-73.2c6.5-5.9 16.7-5.5 22.6 1 6 6.5 5.5 16.6-1 22.6l-26.1 23.9L504 313.8c2.9 2.4 5.5 5 7.9 7.7V128l-54.6-54.6c-5.9-6-14.1-9.4-22.6-9.4zM544 128.2v223.9c0 17.7 14.3 32 32 32h64V128.2h-96zm48 223.9c-8.8 0-16-7.2-16-16s7.2-16 16-16 16 7.2 16 16-7.2 16-16 16zM0 384h64c17.7 0 32-14.3 32-32V128.2H0V384zm48-63.9c8.8 0 16 7.2 16 16s-7.2 16-16 16-16-7.2-16-16c0-8.9 7.2-16 16-16zm435.9 18.6L334.6 217.5l-30 27.5c-29.7 27.1-75.2 24.5-101.7-4.4-26.9-29.4-24.8-74.9 4.4-101.7L289.1 64h-83.8c-8.5 0-16.6 3.4-22.6 9.4L128 128v223.9h18.3l90.5 81.9c27.4 22.3 67.7 18.1 90-9.3l.2-.2 17.9 15.5c15.9 13 39.4 10.5 52.3-5.4l31.4-38.6 5.4 4.4c13.7 11.1 33.9 9.1 45-4.7l9.5-11.7c11.2-13.8 9.1-33.9-4.6-45.1z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tKOOPERATION\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tArbeite mit uns zusammen\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df41821 sc_fly_static elementor-widget elementor-widget-button\" data-id=\"df41821\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/unitedhandsforrefugees.org\/de\/get-involved\/#collaborate\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontakt<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd20905 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"fd20905\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Beachte: Donorbox sch\u00fctzt  Kontodaten und personenbezogene Daten mittels SSL\/TLS Encryption Technologie und ist daher eine sichere Zahlungsoption.<\/p>\n<p>Wenn du deine Spende lieber direkt \u00fcberweisen m\u00f6chtest sende sie an:<\/p>\n<p>United Hands for Refugees e.V.<\/p>\n<p>Bank Name: GLS Gemeinschaftsbank eG<br>IBAN: DE11 4306 0967 1241 0904 00<br>BIC: GENODEM1GLS<br>Referenz:<br>\"SPENDE f\u00fcr United Hands for Refugees\"<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-9ee74cc e-con-full e-flex e-con e-child\" data-id=\"9ee74cc\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0271421 e-con-full e-flex e-con e-child\" data-id=\"0271421\" data-element_type=\"container\" id=\"donate\">\n\t\t\t\t<div class=\"elementor-element elementor-element-873be18 sc_fly_static elementor-widget elementor-widget-html\" data-id=\"873be18\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script src=\"https:\/\/donorbox.org\/widget.js\" paypalexpress=\"true\"><\/script> <iframe src=\"https:\/\/donorbox.org\/embed\/gbv-campaign-2025?\" name=\"donorbox\" allowpaymentrequest=\"allowpaymentrequest\" seamless=\"seamless\" frameborder=\"0\" scrolling=\"no\" height=\"900px\" width=\"100%\" style=\"max-width: 500px; min-width: 250px; max-height:none!important\" allow=\"payment\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0deee40 e-flex e-con-boxed e-con e-parent\" data-id=\"0deee40\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Join us as we seek Protection &amp; Justice for Yazidi Genocide Survivors \u2013 Speaking out for women facing Sexual &amp; Gender-Based Violence On behalf of us all, we request that you hear our devastating silence. Donate In August 2014, the so-called Islamic State (ISIS) targeted the Yazidi people in Sinjar, Iraq, killing over 5,000 men,&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8839","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.1 (Yoast SEO v24.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>GBV Campaign 2025 - United Hands for Refugees e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unitedhandsforrefugees.org\/de\/gbv-campaign-2025\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GBV Campaign 2025\" \/>\n<meta property=\"og:description\" content=\"Join us as we seek Protection &amp; Justice for Yazidi Genocide Survivors \u2013 Speaking out for women facing Sexual &amp; Gender-Based Violence On behalf of us all, we request that you hear our devastating silence. Donate In August 2014, the so-called Islamic State (ISIS) targeted the Yazidi people in Sinjar, Iraq, killing over 5,000 men,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unitedhandsforrefugees.org\/de\/gbv-campaign-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"United Hands for Refugees e.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unitedhandsforrefugees\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T22:14:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1428\" \/>\n\t<meta property=\"og:image:height\" content=\"1553\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/\",\"url\":\"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/\",\"name\":\"GBV Campaign 2025 - United Hands for Refugees e.V.\",\"isPartOf\":{\"@id\":\"https:\/\/unitedhandsforrefugees.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-150x150.png\",\"datePublished\":\"2025-05-19T10:58:42+00:00\",\"dateModified\":\"2025-06-26T22:14:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/#primaryimage\",\"url\":\"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-150x150.png\",\"contentUrl\":\"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-150x150.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/unitedhandsforrefugees.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GBV Campaign 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unitedhandsforrefugees.org\/#website\",\"url\":\"https:\/\/unitedhandsforrefugees.org\/\",\"name\":\"United Hands for Refugees e.V.\",\"description\":\"Newsletter\",\"publisher\":{\"@id\":\"https:\/\/unitedhandsforrefugees.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unitedhandsforrefugees.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/unitedhandsforrefugees.org\/#organization\",\"name\":\"United Hands for Refugees e.V.\",\"alternateName\":\"UHfR\",\"url\":\"https:\/\/unitedhandsforrefugees.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/unitedhandsforrefugees.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2024\/11\/UHfR-Logo-Horizontal.png\",\"contentUrl\":\"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2024\/11\/UHfR-Logo-Horizontal.png\",\"width\":2890,\"height\":822,\"caption\":\"United Hands for Refugees e.V.\"},\"image\":{\"@id\":\"https:\/\/unitedhandsforrefugees.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unitedhandsforrefugees\",\"https:\/\/www.instagram.com\/unitedhandsforrefugees\/\",\"https:\/\/www.linkedin.com\/company\/united-hands-for-refugees\/\"],\"description\":\"UHfR is a non-profit association supporting refugees and displaced communities.\",\"email\":\"info@unitedhandsforrefugees.org\",\"legalName\":\"United Hands for Refugees e.V.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GBV Campaign 2025 - United Hands for Refugees e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unitedhandsforrefugees.org\/de\/gbv-campaign-2025\/","og_locale":"de_DE","og_type":"article","og_title":"GBV Campaign 2025","og_description":"Join us as we seek Protection &amp; Justice for Yazidi Genocide Survivors \u2013 Speaking out for women facing Sexual &amp; Gender-Based Violence On behalf of us all, we request that you hear our devastating silence. Donate In August 2014, the so-called Islamic State (ISIS) targeted the Yazidi people in Sinjar, Iraq, killing over 5,000 men,&hellip;","og_url":"https:\/\/unitedhandsforrefugees.org\/de\/gbv-campaign-2025\/","og_site_name":"United Hands for Refugees e.V.","article_publisher":"https:\/\/www.facebook.com\/unitedhandsforrefugees","article_modified_time":"2025-06-26T22:14:07+00:00","og_image":[{"width":1428,"height":1553,"url":"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/","url":"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/","name":"GBV Campaign 2025 - United Hands for Refugees e.V.","isPartOf":{"@id":"https:\/\/unitedhandsforrefugees.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/#primaryimage"},"image":{"@id":"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-150x150.png","datePublished":"2025-05-19T10:58:42+00:00","dateModified":"2025-06-26T22:14:07+00:00","breadcrumb":{"@id":"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/#primaryimage","url":"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-150x150.png","contentUrl":"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2025\/06\/icon-fight-p-150x150.png"},{"@type":"BreadcrumbList","@id":"https:\/\/unitedhandsforrefugees.org\/gbv-campaign-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/unitedhandsforrefugees.org\/"},{"@type":"ListItem","position":2,"name":"GBV Campaign 2025"}]},{"@type":"WebSite","@id":"https:\/\/unitedhandsforrefugees.org\/#website","url":"https:\/\/unitedhandsforrefugees.org\/","name":"United Hands for Refugees e.V.","description":"Newsletter","publisher":{"@id":"https:\/\/unitedhandsforrefugees.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unitedhandsforrefugees.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/unitedhandsforrefugees.org\/#organization","name":"United Hands for Refugees e.V.","alternateName":"UHfR","url":"https:\/\/unitedhandsforrefugees.org\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/unitedhandsforrefugees.org\/#\/schema\/logo\/image\/","url":"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2024\/11\/UHfR-Logo-Horizontal.png","contentUrl":"https:\/\/unitedhandsforrefugees.org\/wp-content\/uploads\/2024\/11\/UHfR-Logo-Horizontal.png","width":2890,"height":822,"caption":"United Hands for Refugees e.V."},"image":{"@id":"https:\/\/unitedhandsforrefugees.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unitedhandsforrefugees","https:\/\/www.instagram.com\/unitedhandsforrefugees\/","https:\/\/www.linkedin.com\/company\/united-hands-for-refugees\/"],"description":"UHfR is a non-profit association supporting refugees and displaced communities.","email":"info@unitedhandsforrefugees.org","legalName":"United Hands for Refugees e.V."}]}},"_links":{"self":[{"href":"https:\/\/unitedhandsforrefugees.org\/de\/wp-json\/wp\/v2\/pages\/8839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unitedhandsforrefugees.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/unitedhandsforrefugees.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/unitedhandsforrefugees.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unitedhandsforrefugees.org\/de\/wp-json\/wp\/v2\/comments?post=8839"}],"version-history":[{"count":161,"href":"https:\/\/unitedhandsforrefugees.org\/de\/wp-json\/wp\/v2\/pages\/8839\/revisions"}],"predecessor-version":[{"id":9432,"href":"https:\/\/unitedhandsforrefugees.org\/de\/wp-json\/wp\/v2\/pages\/8839\/revisions\/9432"}],"wp:attachment":[{"href":"https:\/\/unitedhandsforrefugees.org\/de\/wp-json\/wp\/v2\/media?parent=8839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}